{"id":644,"date":"2022-10-04T20:34:08","date_gmt":"2022-10-04T20:34:08","guid":{"rendered":"https:\/\/saludsanbernardino.com.ve\/?p=644"},"modified":"2022-10-08T15:32:10","modified_gmt":"2022-10-08T15:32:10","slug":"un-epicentro-medico-en-caracas","status":"publish","type":"post","link":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/","title":{"rendered":"Un epicentro m\u00e9dico en Caracas"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<blockquote>\n<h1>Blog<\/h1>\n<\/blockquote>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Ubicada al noreste del municipio Libertador y limitando al sur del Parque Nacional El \u00c1vila se encuentran los 12,27 kil\u00f3metros cuadrados que comprenden la parroquia de San Bernardino, un espacio geogr\u00e1fico que re\u00fane las condiciones id\u00f3neas para la creaci\u00f3n de una Zona Econ\u00f3mica Especial centrada en Salud. Dentro de sus l\u00edmites hay m\u00e1s de 45 centros m\u00e9dicos, sin incluir laboratorios y centros de asistencia social, lo que lo convierte en el \u00e1rea de Venezuela que m\u00e1s re\u00fane instituciones de atenci\u00f3n m\u00e9dica en un solo lugar. Entre sus calles florece una cultura m\u00e9dica que tiene m\u00e1s de 80 a\u00f1os de crecimiento desde la fundaci\u00f3n del Hospital J.M. de los R\u00edos, inaugurado en 1937 bajo sus faldas cuando los terrenos apenas perd\u00edan el hedor a caf\u00e9 de las haciendas de Vollmer.\u00a0<\/span><span style=\"font-weight: 400;\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-1-300x202.jpg\" width=\"300\" height=\"202\" alt=\"\" class=\"wp-image-646 alignleft size-medium\" \/>En ese entonces San Bernardino estaba siendo transformada en un conjunto residencial de quintas para satisfacer las necesidades de una reciente burgues\u00eda que gestaba los tiempos de bonanza petrolera. El dise\u00f1o de la zona fue otorgado a Maurice Rotival, quien le da una importancia a mantener la decoraci\u00f3n vegetal que daban la arboleda de la zona y el fondo donde protagoniza el \u00c1vila, adem\u00e1s de brindarle una vital atenci\u00f3n a la vialidad, de manera que se construir\u00edan largas avenidas de ambos sentidos. Ambas cosas ser\u00edan (sin las intenciones de serlo) grandes ventajas para los centros m\u00e9dicos que a\u00f1os m\u00e1s tarde empezar\u00edan a brotar entre sus calles. Las avenidas que hacen una conexi\u00f3n de f\u00e1cil acceso al resto de la ciudad, y la naturaleza que da a los espacios m\u00e9dicos un espacio de mayor paz al estar separados de la aglomeraci\u00f3n citadina.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En 1947 se inaugura el Centro M\u00e9dico de Caracas, que para el momento era el edificio de servicio m\u00e1s importante de la zona. Para la fecha Venezuela empieza a recibir una ola de inmigrantes escapando de las garras de la segunda guerra mundial. Esto influye directamente sobre la arquitectura de la zona donde empiezan a levantarse apartamentos de cuatro a seis pisos con locales comerciales en la planta baja (una prueba de la influencia de la diversidad en la esencia de las calles caraque\u00f1as y su cultura social). Adem\u00e1s de esto se plantea el plan regulador para frenar una desviaci\u00f3n de sus intenciones urban\u00edsticas, por lo que se limita la construcci\u00f3n a edificios religiosos, escolares y de salud. Otro punto importante que fomentar\u00eda la proliferaci\u00f3n de centros m\u00e9dicos en San Bernardino.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2--300x291.jpg\" width=\"300\" height=\"291\" alt=\"\" class=\"wp-image-642 alignleft size-medium\" \/>Entre los 50 y los 70 la poblaci\u00f3n en Caracas empieza a crecer de una manera vertiginosa, y con ella sus necesidades. Las \u00e1reas verdes de San Bernardino se convierten en zonas populares o barrios, y los servicios en el sector de salud se aceleran. Se fundan el Hospital de Cl\u00ednica Caracas, la Cl\u00ednica \u201cLa Esmeralda\u201d, \u201cLa Arboleda\u201d, el Instituto Otorrino, entre muchas otras; que tambi\u00e9n fomentaron la docencia y c\u00e1tedra experiencial para estudiantes de medicina. Citando al doctor Alfredo Kaufman, socio fundador del Hospital de Cl\u00ednica Caracas, <\/span><i><span style=\"font-weight: 400;\">\u201cpara el momento el gobierno hab\u00eda ofrecido para las instituciones prestadoras de salud un cr\u00e9dito preferencial de 8% anual fijo\u201d, <\/span><\/i><span style=\"font-weight: 400;\">tal explica la r\u00e1pida multiplicaci\u00f3n de centros de atenci\u00f3n m\u00e9dica en una zona id\u00f3nea para los mismos, un reflejo de lo mismo en que desde 1976 hasta 1981 el n\u00famero de consultorios aument\u00f3 18 veces en el sector privado y cinco veces en los p\u00fablicos (Brice\u00f1o Le\u00f3n, 1990)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La cultura de San Bernardino est\u00e1 en su urbanidad. Un paseo por sus calles es m\u00e1s que suficiente para ver el crecimiento hist\u00f3rico que lo ha convertido en lo que es hoy. Hogar de una cultura tan diversa que su mezcla heterog\u00e9nea es puramente venezolana y de los centros de salud m\u00e1s importantes de Caracas que han hecho de San Bernardino un epicentro m\u00e9dico en el pa\u00eds que todav\u00eda sigue dando pasos para convertirse en un referente de la medicina en Latinoam\u00e9rica.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog Ubicada al noreste del municipio Libertador y limitando al sur del Parque Nacional El \u00c1vila se encuentran los 12,27 kil\u00f3metros cuadrados que comprenden la parroquia de San Bernardino, un espacio geogr\u00e1fico que re\u00fane las condiciones id\u00f3neas para la creaci\u00f3n de una Zona Econ\u00f3mica Especial centrada en Salud. Dentro de sus l\u00edmites hay m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[102],"tags":[],"class_list":["post-644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino\" \/>\n<meta property=\"og:description\" content=\"Blog Ubicada al noreste del municipio Libertador y limitando al sur del Parque Nacional El \u00c1vila se encuentran los 12,27 kil\u00f3metros cuadrados que comprenden la parroquia de San Bernardino, un espacio geogr\u00e1fico que re\u00fane las condiciones id\u00f3neas para la creaci\u00f3n de una Zona Econ\u00f3mica Especial centrada en Salud. Dentro de sus l\u00edmites hay m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/\" \/>\n<meta property=\"og:site_name\" content=\"Zona de Salud San Bernardino\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-04T20:34:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-08T15:32:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/\"},\"author\":{\"name\":\"Fundaci\u00f3n San Bernardino\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"headline\":\"Un epicentro m\u00e9dico en Caracas\",\"datePublished\":\"2022-10-04T20:34:08+00:00\",\"dateModified\":\"2022-10-08T15:32:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/\"},\"wordCount\":787,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Imagen-2-.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/\",\"name\":\"Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Imagen-2-.jpg\",\"datePublished\":\"2022-10-04T20:34:08+00:00\",\"dateModified\":\"2022-10-08T15:32:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Imagen-2-.jpg\",\"contentUrl\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Imagen-2-.jpg\",\"width\":709,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/04\\\/un-epicentro-medico-en-caracas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un epicentro m\u00e9dico en Caracas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\",\"name\":\"Zona de Salud San Bernardino\",\"description\":\"Directorio de especialidades medicas y cl\u00ednicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\",\"name\":\"Fundaci\u00f3n San Bernardino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n San Bernardino\"},\"sameAs\":[\"https:\\\/\\\/saludsanbernardino.com.ve\"],\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/author\\\/ssb_m5lizpt0\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/","og_locale":"es_ES","og_type":"article","og_title":"Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino","og_description":"Blog Ubicada al noreste del municipio Libertador y limitando al sur del Parque Nacional El \u00c1vila se encuentran los 12,27 kil\u00f3metros cuadrados que comprenden la parroquia de San Bernardino, un espacio geogr\u00e1fico que re\u00fane las condiciones id\u00f3neas para la creaci\u00f3n de una Zona Econ\u00f3mica Especial centrada en Salud. Dentro de sus l\u00edmites hay m\u00e1s de [&hellip;]","og_url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/","og_site_name":"Zona de Salud San Bernardino","article_published_time":"2022-10-04T20:34:08+00:00","article_modified_time":"2022-10-08T15:32:10+00:00","og_image":[{"width":709,"height":688,"url":"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg","type":"image\/jpeg"}],"author":"Fundaci\u00f3n San Bernardino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n San Bernardino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#article","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/"},"author":{"name":"Fundaci\u00f3n San Bernardino","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"headline":"Un epicentro m\u00e9dico en Caracas","datePublished":"2022-10-04T20:34:08+00:00","dateModified":"2022-10-08T15:32:10+00:00","mainEntityOfPage":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/"},"wordCount":787,"commentCount":0,"image":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg","articleSection":["blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/","url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/","name":"Un epicentro m\u00e9dico en Caracas - Zona de Salud San Bernardino","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#primaryimage"},"image":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#primaryimage"},"thumbnailUrl":"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg","datePublished":"2022-10-04T20:34:08+00:00","dateModified":"2022-10-08T15:32:10+00:00","author":{"@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"breadcrumb":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#primaryimage","url":"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg","contentUrl":"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Imagen-2-.jpg","width":709,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/04\/un-epicentro-medico-en-caracas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saludsanbernardino.com.ve\/"},{"@type":"ListItem","position":2,"name":"Un epicentro m\u00e9dico en Caracas"}]},{"@type":"WebSite","@id":"https:\/\/saludsanbernardino.com.ve\/#website","url":"https:\/\/saludsanbernardino.com.ve\/","name":"Zona de Salud San Bernardino","description":"Directorio de especialidades medicas y cl\u00ednicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saludsanbernardino.com.ve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178","name":"Fundaci\u00f3n San Bernardino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","caption":"Fundaci\u00f3n San Bernardino"},"sameAs":["https:\/\/saludsanbernardino.com.ve"],"url":"https:\/\/saludsanbernardino.com.ve\/index.php\/author\/ssb_m5lizpt0\/"}]}},"_links":{"self":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":2,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/644\/revisions"}],"predecessor-version":[{"id":647,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/644\/revisions\/647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/media\/642"}],"wp:attachment":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/media?parent=644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/categories?post=644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/tags?post=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}