{"id":1318,"date":"2022-10-08T18:45:00","date_gmt":"2022-10-08T18:45:00","guid":{"rendered":"https:\/\/saludsanbernardino.com.ve\/?p=1318"},"modified":"2022-10-09T22:39:17","modified_gmt":"2022-10-09T22:39:17","slug":"patologia-en-san-bernardino","status":"publish","type":"post","link":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/","title":{"rendered":"Patolog\u00eda, pat\u00f3logo en San Bernardino"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<h2>Especialistas en Patolog\u00eda.<\/h2>\n<h4>Anatom\u00eds patol\u00f3gica, pat\u00f3logo<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<table border=\"1\" style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\">Sonia Mar\u00eda Dickson Gonz\u00e1lez<\/td>\n<td style=\"width: 50%;\">Hospital de CL\u00ednicas Caracas<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><span>Francis Guevara<\/span><\/td>\n<td style=\"width: 50%;\">Cl\u00ednica F\u00e9nix Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><span>Gustavo Parthe<\/span><span><br \/><\/span><\/td>\n<td style=\"width: 50%;\">Cl\u00ednica F\u00e9nix Salud<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Especialistas en Patolog\u00eda. Anatom\u00eds patol\u00f3gica, pat\u00f3logo Sonia Mar\u00eda Dickson Gonz\u00e1lez Hospital de CL\u00ednicas Caracas Francis Guevara Cl\u00ednica F\u00e9nix Salud Gustavo Parthe Cl\u00ednica F\u00e9nix Salud<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[132],"tags":[],"class_list":["post-1318","post","type-post","status-publish","format-standard","hentry","category-patologo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino\" \/>\n<meta property=\"og:description\" content=\"Especialistas en Patolog\u00eda. Anatom\u00eds patol\u00f3gica, pat\u00f3logo Sonia Mar\u00eda Dickson Gonz\u00e1lez Hospital de CL\u00ednicas Caracas Francis Guevara Cl\u00ednica F\u00e9nix Salud Gustavo Parthe Cl\u00ednica F\u00e9nix Salud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/\" \/>\n<meta property=\"og:site_name\" content=\"Zona de Salud San Bernardino\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-08T18:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-09T22:39:17+00:00\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/\"},\"author\":{\"name\":\"Fundaci\u00f3n San Bernardino\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"headline\":\"Patolog\u00eda, pat\u00f3logo en San Bernardino\",\"datePublished\":\"2022-10-08T18:45:00+00:00\",\"dateModified\":\"2022-10-09T22:39:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/\"},\"wordCount\":120,\"articleSection\":[\"Pat\u00f3logo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/\",\"name\":\"Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\"},\"datePublished\":\"2022-10-08T18:45:00+00:00\",\"dateModified\":\"2022-10-09T22:39:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/patologia-en-san-bernardino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patolog\u00eda, pat\u00f3logo en San Bernardino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\",\"name\":\"Zona de Salud San Bernardino\",\"description\":\"Directorio de especialidades medicas y cl\u00ednicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\",\"name\":\"Fundaci\u00f3n San Bernardino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n San Bernardino\"},\"sameAs\":[\"https:\\\/\\\/saludsanbernardino.com.ve\"],\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/author\\\/ssb_m5lizpt0\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/","og_locale":"es_ES","og_type":"article","og_title":"Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino","og_description":"Especialistas en Patolog\u00eda. Anatom\u00eds patol\u00f3gica, pat\u00f3logo Sonia Mar\u00eda Dickson Gonz\u00e1lez Hospital de CL\u00ednicas Caracas Francis Guevara Cl\u00ednica F\u00e9nix Salud Gustavo Parthe Cl\u00ednica F\u00e9nix Salud","og_url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/","og_site_name":"Zona de Salud San Bernardino","article_published_time":"2022-10-08T18:45:00+00:00","article_modified_time":"2022-10-09T22:39:17+00:00","author":"Fundaci\u00f3n San Bernardino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n San Bernardino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/#article","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/"},"author":{"name":"Fundaci\u00f3n San Bernardino","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"headline":"Patolog\u00eda, pat\u00f3logo en San Bernardino","datePublished":"2022-10-08T18:45:00+00:00","dateModified":"2022-10-09T22:39:17+00:00","mainEntityOfPage":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/"},"wordCount":120,"articleSection":["Pat\u00f3logo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/","url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/","name":"Patolog\u00eda, pat\u00f3logo en San Bernardino - Zona de Salud San Bernardino","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/#website"},"datePublished":"2022-10-08T18:45:00+00:00","dateModified":"2022-10-09T22:39:17+00:00","author":{"@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"breadcrumb":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saludsanbernardino.com.ve\/"},{"@type":"ListItem","position":2,"name":"Patolog\u00eda, pat\u00f3logo en San Bernardino"}]},{"@type":"WebSite","@id":"https:\/\/saludsanbernardino.com.ve\/#website","url":"https:\/\/saludsanbernardino.com.ve\/","name":"Zona de Salud San Bernardino","description":"Directorio de especialidades medicas y cl\u00ednicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saludsanbernardino.com.ve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178","name":"Fundaci\u00f3n San Bernardino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","caption":"Fundaci\u00f3n San Bernardino"},"sameAs":["https:\/\/saludsanbernardino.com.ve"],"url":"https:\/\/saludsanbernardino.com.ve\/index.php\/author\/ssb_m5lizpt0\/"}]}},"_links":{"self":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/comments?post=1318"}],"version-history":[{"count":4,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1318\/revisions"}],"predecessor-version":[{"id":1411,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1318\/revisions\/1411"}],"wp:attachment":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/media?parent=1318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/categories?post=1318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/tags?post=1318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}