{"id":1293,"date":"2022-10-08T18:11:11","date_gmt":"2022-10-08T18:11:11","guid":{"rendered":"https:\/\/saludsanbernardino.com.ve\/?p=1293"},"modified":"2022-10-08T22:07:26","modified_gmt":"2022-10-08T22:07:26","slug":"neurocirugia-pediatrica-en-san-bernardino","status":"publish","type":"post","link":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/","title":{"rendered":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Neurocirug\u00eda pedi\u00e1trica, neurocirujano pedi\u00e1trico en la zona la salud de San Bernardino, muy pronto.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neurocirug\u00eda pedi\u00e1trica, neurocirujano pedi\u00e1trico en la zona la salud de San Bernardino, muy pronto.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[140,1],"tags":[],"class_list":["post-1293","post","type-post","status-publish","format-standard","hentry","category-neurocirujano-pediatrico","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino\" \/>\n<meta property=\"og:description\" content=\"Neurocirug\u00eda pedi\u00e1trica, neurocirujano pedi\u00e1trico en la zona la salud de San Bernardino, muy pronto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/\" \/>\n<meta property=\"og:site_name\" content=\"Zona de Salud San Bernardino\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-08T18:11:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-08T22:07:26+00:00\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n San Bernardino\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/\"},\"author\":{\"name\":\"Fundaci\u00f3n San Bernardino\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"headline\":\"Neurocirug\u00eda pedi\u00e1trica en San Bernardino\",\"datePublished\":\"2022-10-08T18:11:11+00:00\",\"dateModified\":\"2022-10-08T22:07:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/\"},\"wordCount\":87,\"articleSection\":[\"neurocirujano pedi\u00e1trico\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/\",\"name\":\"Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\"},\"datePublished\":\"2022-10-08T18:11:11+00:00\",\"dateModified\":\"2022-10-08T22:07:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/2022\\\/10\\\/08\\\/neurocirugia-pediatrica-en-san-bernardino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neurocirug\u00eda pedi\u00e1trica en San Bernardino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\",\"name\":\"Zona de Salud San Bernardino\",\"description\":\"Directorio de especialidades medicas y cl\u00ednicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#\\\/schema\\\/person\\\/66c6457b3fe2378a165c988abf0f5178\",\"name\":\"Fundaci\u00f3n San Bernardino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n San Bernardino\"},\"sameAs\":[\"https:\\\/\\\/saludsanbernardino.com.ve\"],\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/author\\\/ssb_m5lizpt0\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/","og_locale":"es_ES","og_type":"article","og_title":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino","og_description":"Neurocirug\u00eda pedi\u00e1trica, neurocirujano pedi\u00e1trico en la zona la salud de San Bernardino, muy pronto.","og_url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/","og_site_name":"Zona de Salud San Bernardino","article_published_time":"2022-10-08T18:11:11+00:00","article_modified_time":"2022-10-08T22:07:26+00:00","author":"Fundaci\u00f3n San Bernardino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n San Bernardino"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/#article","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/"},"author":{"name":"Fundaci\u00f3n San Bernardino","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"headline":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino","datePublished":"2022-10-08T18:11:11+00:00","dateModified":"2022-10-08T22:07:26+00:00","mainEntityOfPage":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/"},"wordCount":87,"articleSection":["neurocirujano pedi\u00e1trico","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/","url":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/","name":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino - Zona de Salud San Bernardino","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/#website"},"datePublished":"2022-10-08T18:11:11+00:00","dateModified":"2022-10-08T22:07:26+00:00","author":{"@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178"},"breadcrumb":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-pediatrica-en-san-bernardino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saludsanbernardino.com.ve\/"},{"@type":"ListItem","position":2,"name":"Neurocirug\u00eda pedi\u00e1trica en San Bernardino"}]},{"@type":"WebSite","@id":"https:\/\/saludsanbernardino.com.ve\/#website","url":"https:\/\/saludsanbernardino.com.ve\/","name":"Zona de Salud San Bernardino","description":"Directorio de especialidades medicas y cl\u00ednicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saludsanbernardino.com.ve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/saludsanbernardino.com.ve\/#\/schema\/person\/66c6457b3fe2378a165c988abf0f5178","name":"Fundaci\u00f3n San Bernardino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/482f2280805dcdc870257928de8050828995a7178ea82e8f790aad57bd00d424?s=96&d=mm&r=g","caption":"Fundaci\u00f3n San Bernardino"},"sameAs":["https:\/\/saludsanbernardino.com.ve"],"url":"https:\/\/saludsanbernardino.com.ve\/index.php\/author\/ssb_m5lizpt0\/"}]}},"_links":{"self":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/comments?post=1293"}],"version-history":[{"count":3,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1293\/revisions"}],"predecessor-version":[{"id":1373,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts\/1293\/revisions\/1373"}],"wp:attachment":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/media?parent=1293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/categories?post=1293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/tags?post=1293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}