{"id":191,"date":"2022-10-03T03:14:11","date_gmt":"2022-10-03T03:14:11","guid":{"rendered":"https:\/\/saludsanbernardino.com.ve\/?page_id=191"},"modified":"2022-10-10T21:57:53","modified_gmt":"2022-10-10T21:57:53","slug":"directorio-medico","status":"publish","type":"page","link":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/","title":{"rendered":"Directorio m\u00e9dico"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.18.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_direction_radial=\u00bbtop left\u00bb background_color_gradient_stops=\u00bbrgba(0,79,140,0.34) 0%|#00385e 50%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,79,140,0.34)\u00bb background_color_gradient_end=\u00bb#00385e\u00bb background_color_gradient_end_position=\u00bb50%\u00bb background_image=\u00bbhttps:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/especialidades-medicas-en-caracas.png\u00bb custom_padding=\u00bb10vh|0|12vh||false|false\u00bb custom_padding_tablet=\u00bb10vh||10vh||false\u00bb custom_padding_phone=\u00bb5vh||5vh||false\u00bb top_divider_style=\u00bbwave2&#8243; top_divider_color=\u00bbrgba(12,113,195,0.11)\u00bb top_divider_height=\u00bb460px\u00bb top_divider_flip=\u00bbhorizontal\u00bb bottom_divider_style=\u00bbcurve\u00bb bottom_divider_color=\u00bb#ffffff\u00bb bottom_divider_height=\u00bb3vw\u00bb bottom_divider_flip=\u00bbvertical\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; text_font=\u00bbPoppins||||||||\u00bb text_font_size=\u00bb8px\u00bb text_line_height=\u00bb1.5em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb64px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.2em\u00bb header_2_font=\u00bbVollkorn||||||||\u00bb header_2_font_size=\u00bb44px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bb||||||||\u00bb header_4_font=\u00bb||||||||\u00bb header_5_font=\u00bb||||||||\u00bb header_6_font=\u00bb||||||||\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||20px|\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb2%\u00bb header_font_size_tablet=\u00bb35px\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Directorio M\u00e9dico<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/Logo-nuevo-blanco2-de-zona-economica.png\u00bb alt=\u00bbzona de econom\u00eda y salud en caracas distrito capital\u00bb title_text=\u00bbLogo nuevo blanco2 de zona economica\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0|0px|0|0px|false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_delay=\u00bb400ms\u00bb animation_intensity_slide=\u00bb2%\u00bb use_custom_width=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_button button_text=\u00bbcont\u00e1cto\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.18.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#1e4278&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbLibre Franklin|600|||||||\u00bb button_icon=\u00bb&#xe090;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb16px|26px|16px|44px|true|false\u00bb button_letter_spacing_hover=\u00bb1px\u00bb button_bg_color_hover=\u00bb#236299&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb1px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#236299&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_button button_text=\u00bbDirectorio general\u00bb _builder_version=\u00bb4.18.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbLibre Franklin|600|||||||\u00bb button_icon=\u00bb&#x44;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb16px|26px|16px|44px|true|false\u00bb hover_enabled=\u00bb0&#8243; button_letter_spacing_hover=\u00bb1px\u00bb button_bg_color_hover=\u00bb#27d8d2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb1px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#27d8d2&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_url=\u00bbhttps:\/\/saludsanbernardino.com.ve\/index.php\/directorios-zona-especial-de-salud-san-bernardino\/\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider color=\u00bbrgba(255,255,255,0.2)\u00bb divider_position=\u00bbbottom\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbServices\u00bb _builder_version=\u00bb4.18.0&#8243; background_enable_color=\u00bboff\u00bb custom_padding=\u00bb55px|0px|14px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"wpas-advanced-search-form-container wpas_form_container_1\">\n\t\t\t<h3>buscar<\/h3>\n\t\t\t<div class=\"wpas_wrapper\">\n\t\t<form id=\"wpas-advanced-search-form_1\" role=\"search\" method=\"POST\" class=\"wpas_search_form search_form_1\" action=\"\" onkeydown=\"return event.key != 'Enter';\">\n\t\t<input type=\"hidden\" name=\"form_id\" value=\"1\" \/>\n\t\t<div class=\"input_cont right\">\n\t\t\t<div class=\"wpas_input_container\" id=\"wpas_input_container_1\">\n\t\t\t\t<div class=\"input_box\"><input required class=\"wpas_search_input\" id=\"wpas_search_input_1\" type=\"search\" placeholder=\"Search here...\" name=\"advance-search_1\" data-formid=\"1\" \/>\n\t\t\t\t<\/label>\n\t\t\t\t<div class=\"wpas_search_loader_icon\" style=\"display:none;\"><div class=\"sbl-circ\"><\/div><\/div>\n\t<div class=\"wpas_search_close\">\n\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"40px\" height=\"40px\" viewBox=\"0 0 512 512\" enable-background=\"new 0 0 512 512\" xml:space=\"preserve\">\n\t\t\t\t<polygon id=\"x-mark-icon\" points=\"438.393,374.595 319.757,255.977 438.378,137.348 374.595,73.607 255.995,192.225 137.375,73.622 73.607,137.352 192.246,255.983 73.622,374.625 137.352,438.393 256.002,319.734 374.652,438.378 \"><\/polygon>\n\t\t\t\t<\/svg>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wpas_submit_wrapper\"><div class=\"wpas_margnifire_icon\"><i class=\"fa fa-search\"><\/i> <div class=\"button_text_holder\">Search<\/div><div class=\"new_icon_div\"><\/div><\/div>\n\t\t\t<\/div> <!-- wpas-input-container -->\n\t<\/div>\n\t\t\t<div class=\"wpas_search_result\" style=\"display:none;\"><\/div>\n\t\t<\/form> <!-- wpas-advanced-search-for -->\n\t\t<\/div>\n\t<\/div> <!-- wpas-advanced-search-form-container -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,3_5,1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb27px|0px|0|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider color=\u00bbrgba(0,0,0,0.08)\u00bb divider_position=\u00bbbottom\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.16&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbright\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; text_font=\u00bbPoppins||||||||\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bbPoppins||||||||\u00bb header_2_font=\u00bbVollkorn||||||||\u00bb header_2_font_size=\u00bb35px\u00bb header_2_line_height=\u00bb1.4em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb600px\u00bb module_alignment=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb inline_fonts=\u00bbPoppins\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"font-family: Poppins; color: #052187;\">Lista de M\u00e9dicos Especialistas<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider color=\u00bbrgba(0,0,0,0.08)\u00bb divider_position=\u00bbbottom\u00bb divider_weight=\u00bb2px\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.16&#8243; animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbObituaries\u00bb _builder_version=\u00bb4.18.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(8,24,73,0) 0%|#2b87da 72%\u00bb background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbdiagonal-stripes-2&#8243; background_pattern_color=\u00bbrgba(0,0,0,0.01)\u00bb custom_padding=\u00bb32px|||||\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb-48px|auto||auto||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion closed_toggle_text_color=\u00bb#FFFFFF\u00bb closed_toggle_background_color=\u00bb#041056&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb82%\u00bb max_width=\u00bb100%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|-54px||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbAlerg\u00f3logo\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/09\/alergologo-en-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbAnestesi\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/anestesiologos-en-la-zona-de-salud-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCardi\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cardiologos-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCardi\u00f3logo pediatra\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cardiologo-pediatra-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano bari\u00e1trico  \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cirujano-bariatrico-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano cardiovascular \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cirujano-cardiovascular-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano de cabeza y cuello\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/09\/cirujano-de-cabeza-y-cuello-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano de la mano \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cirujanos-de-la-mano-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano general \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cirujano-general-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano maxilofacial\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/09\/cirujano-maxilofacial-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano pl\u00e1stico \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/cirujano-plastico-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano pediatra\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/09\/cirujano-pediatra-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbCirujano de t\u00f3rax\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/cirujano-de-torax-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbColoproctolog\u00eda \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/coloproctologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbDermat\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/?p=1230&amp;et_fb=1&amp;PageSpeed=off\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbEndocrinos\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/endocrino-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbFisiatra\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/fisiatra-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbFisioterapia Hospitalaria\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/fisioterapia-hospitalaria-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbFlebolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/flebologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbFonoaudiolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/fonoaudiologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbGastroenter\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/gastroenteroligos-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbGastroenter\u00f3logo pedi\u00e1tra\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/gastroenterologo-pediatra-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbGenetistas\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/genetista-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbGinecolog\u00eda Ginecobstetra\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/?p=1248&amp;et_fb=1&amp;PageSpeed=off\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbGinecolog\u00eda infanto juvenil\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/ginecologo-infanto-juvenil\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbHemat\u00f3logos  \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/hematologos-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbInfect\u00f3logos \u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/infectologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbIntensivistas\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/intensivistas-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbInternistas\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/internistas-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion closed_toggle_text_color=\u00bb#FFFFFF\u00bb closed_toggle_background_color=\u00bb#041056&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb82%\u00bb max_width=\u00bb100%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|||-23px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bbMast\u00f3logo\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/mastologos-en-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbMedicina cr\u00edtica \u00bb open=\u00bboff\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/medicina-critica-en-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbMedicina deportiva\u00bb open=\u00bboff\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/medicina-deportiva-en-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbMedicina ocupacional\u00bb open=\u00bboff\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/medicina-ocupacional-en-san-bernardino\/\">ir al directorio\u00a0<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNefrolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/nefrologo-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNefrolog\u00eda pedi\u00e1trica\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/nefrologo-pediatrica\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNeonatolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/neonatologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNeumon\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neumonologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNeurocirujano\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurocirugia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNeurolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNeur\u00f3logo infantil\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/neurologia-infantil\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbNutri\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/nutriologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOftalm\u00f3logos\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/oftalmologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOnc\u00f3logos\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/oncologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOncolog\u00eda Ortop\u00e9dica\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/oncologia-ortopedica-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOncolog\u00eda pedi\u00e1trica\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/oncologia-pediatrica-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbOtorrinolaring\u00f3logo\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/otorrinolaringologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPatolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/patologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPediatr\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/pediatria-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPerinatolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/perinatologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPsicolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/psicologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbPsiquiatr\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/psiquiatria-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbRadi\u00f3logos\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/radiologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbRehabilitaci\u00f3n\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/rehabilitacion-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbReumatolog\u00eda\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/reumatologo-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbTerapia respiratoria\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/10\/terapia-respiratoria-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbTraumat\u00f3logos ortopedistas\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/traumatologos-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bbUr\u00f3logos\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p><a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/2022\/10\/08\/urologia-en-san-bernardino\/\">Ir al directorio<\/a><\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/saludsanbernardino.com.ve\/index.php\/directorios-zona-especial-de-salud-san-bernardino\/\u00bb button_text=\u00bbRegresar a directorio\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb17px\u00bb button_text_color=\u00bb#0de5e5&#8243; button_bg_color=\u00bb#001551&#8243; button_border_width=\u00bb5px\u00bb button_border_radius=\u00bb60px\u00bb button_icon=\u00bb&#x40;||divi||400&#8243; button_icon_color=\u00bb#FFFFFF\u00bb button_icon_placement=\u00bbleft\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb59px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Blog<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blog fullwidth=\u00bboff\u00bb include_categories=\u00bb102&#8243; excerpt_length=\u00bb100&#8243; show_more=\u00bbon\u00bb show_author=\u00bboff\u00bb show_date=\u00bboff\u00bb masonry_tile_background_color=\u00bb#FFFFFF\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.18.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_direction_radial=\u00bbtop left\u00bb background_color_gradient_stops=\u00bbrgba(0,79,140,0.34) 0%|rgba(0,56,94,0.75) 50%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,79,140,0.34)\u00bb background_color_gradient_end=\u00bbrgba(0,56,94,0.75)\u00bb background_color_gradient_end_position=\u00bb50%\u00bb background_image=\u00bbhttps:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/09\/salud-en-caracas-venezuela.png\u00bb custom_padding=\u00bb10vh|0|12vh||false|false\u00bb custom_padding_tablet=\u00bb10vh||10vh||false\u00bb custom_padding_phone=\u00bb5vh||5vh||false\u00bb top_divider_style=\u00bbwave2&#8243; top_divider_color=\u00bbrgba(12,113,195,0.11)\u00bb top_divider_height=\u00bb600px\u00bb top_divider_flip=\u00bbhorizontal\u00bb bottom_divider_color=\u00bb#ffffff\u00bb bottom_divider_height=\u00bb3vw\u00bb bottom_divider_flip=\u00bbvertical\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; text_font=\u00bbPoppins||||||||\u00bb text_font_size=\u00bb13px\u00bb text_line_height=\u00bb1.2em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb84px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.1em\u00bb header_2_font=\u00bbVollkorn||||||||\u00bb header_2_font_size=\u00bb44px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bb||||||||\u00bb header_4_font=\u00bb||||||||\u00bb header_5_font=\u00bb||||||||\u00bb header_6_font=\u00bb||||||||\u00bb text_orientation=\u00bbright\u00bb background_layout=\u00bbdark\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||16px||false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb2%\u00bb header_font_size_tablet=\u00bb35px\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|desktop\u00bb header_2_font_size_tablet=\u00bb35px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb inline_fonts=\u00bbPoppins\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><span style=\"font-family: Poppins;\">Zona Especial de Salud de\u00a0 San Bernardino<\/span><\/h3>\n<h2><span style=\"font-family: Poppins;\">Aliados de tu Salu<\/span>d<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_4,1_4&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0|0px|0|0px|false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_delay=\u00bb200ms\u00bb animation_intensity_slide=\u00bb2%\u00bb use_custom_width=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider color=\u00bbrgba(255,255,255,0.2)\u00bb divider_position=\u00bbbottom\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_button button_text=\u00bbCont\u00e1cto\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#1e4278&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbLibre Franklin|600|||||||\u00bb button_icon=\u00bb&#xe090;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb16px|26px|16px|44px|true|false\u00bb button_letter_spacing_hover=\u00bb1px\u00bb button_bg_color_hover=\u00bb#236299&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb1px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#236299&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_button button_text=\u00bbVisita nuestro blog\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.18.0&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb13px\u00bb button_text_color=\u00bb#0C71C3&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bbrgba(0,0,0,0)\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bbLibre Franklin|600|||||||\u00bb button_icon=\u00bb&#x6c;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb background_layout=\u00bbdark\u00bb custom_padding=\u00bb16px|26px|16px|44px|true|false\u00bb hover_enabled=\u00bb0&#8243; button_letter_spacing_hover=\u00bb1px\u00bb button_bg_color_hover=\u00bb#27d8d2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bbon\u00bb button_letter_spacing__hover=\u00bb1px\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#27d8d2&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_url=\u00bbhttps:\/\/saludsanbernardino.com.ve\/index.php\/blog-de-salud\/\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\n\t\t<style>\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box,\n\t\t\t#wpls-logo-showcase-slider-1 .wpls-fix-box img.wp-post-image{max-height:250px; }\n\t\t<\/style>\n\n\t\t<div class=\"wpls-wrap wpls-logo-showcase-slider-wrp wpls-logo-clearfix wpls-design-1 \" data-conf=\"{&quot;slides_column&quot;:&quot;3&quot;,&quot;slides_scroll&quot;:1,&quot;dots&quot;:&quot;true&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;autoplay_interval&quot;:3000,&quot;loop&quot;:&quot;true&quot;,&quot;rtl&quot;:&quot;false&quot;,&quot;speed&quot;:800,&quot;center_mode&quot;:&quot;true&quot;,&quot;lazyload&quot;:&quot;&quot;}\">\n\t\t\t<div class=\"wpls-logo-showcase logo_showcase wpls-logo-slider wpls-center sliderimage_hide_border \" id=\"wpls-logo-showcase-slider-1\" >\n\t\t\t\t<div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/project\/centro-medico-caracas\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/logo-hospital-de-clinicas.png\" alt=\"zona de salud en la parroquia san bernardino\" \/>\n\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/project\/centro-clinico-fenix-salud\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/logo-fenix-salud.png\" alt=\"logotipo de la cl\u00ednica F\u00e9nix Salud\" \/>\n\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/project\/hospital-de-clinicas-caracas\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/logo-clinica.png\" alt=\"centro m\u00e9dico carcas de la fundaci\u00f3n san bernardino\" \/>\n\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/project\/clinica-los-sauces\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/logo-los-sauces.png\" alt=\"centro cl\u00ednico los sauces\" \/>\n\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div><div class=\"wpls-logo-cnt\">\n\t<div class=\"wpls-fix-box\">\n\t\t\t\t<a href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/project\/policlinica-la-arboleda\/\" target=\"_self\">\n\t\t\t<img decoding=\"async\" class=\"wp-post-image\"  src=\"https:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/logo-la-arboleda.png\" alt=\"policlinica la arboleda en zona de salud\" \/>\n\t\t<\/a>\n\t\t\t<\/div>\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.18.0&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_direction_radial=\u00bbtop left\u00bb background_color_gradient_stops=\u00bbrgba(0,79,140,0.34) 0%|#00385e 50%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(0,79,140,0.34)\u00bb background_color_gradient_end=\u00bb#00385e\u00bb background_color_gradient_end_position=\u00bb50%\u00bb background_image=\u00bbhttps:\/\/saludsanbernardino.com.ve\/wp-content\/uploads\/2022\/10\/especialidades-medicas-en-caracas.png\u00bb custom_padding=\u00bb10vh|0|12vh||false|false\u00bb custom_padding_tablet=\u00bb10vh||10vh||false\u00bb custom_padding_phone=\u00bb5vh||5vh||false\u00bb top_divider_style=\u00bbwave2&#8243; top_divider_color=\u00bbrgba(12,113,195,0.11)\u00bb top_divider_height=\u00bb460px\u00bb top_divider_flip=\u00bbhorizontal\u00bb bottom_divider_style=\u00bbcurve\u00bb bottom_divider_color=\u00bb#ffffff\u00bb bottom_divider_height=\u00bb3vw\u00bb bottom_divider_flip=\u00bbvertical\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.18.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; text_font=\u00bbPoppins||||||||\u00bb text_font_size=\u00bb8px\u00bb text_line_height=\u00bb1.5em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb64px\u00bb header_letter_spacing=\u00bb1px\u00bb header_line_height=\u00bb1.2em\u00bb header_2_font=\u00bbVollkorn||||||||\u00bb header_2_font_size=\u00bb44px\u00bb header_2_letter_spacing=\u00bb1px\u00bb header_2_line_height=\u00bb1.4em\u00bb header_3_font=\u00bb||||||||\u00bb header_4_font=\u00bb||||||||\u00bb header_5_font=\u00bb||||||||\u00bb header_6_font=\u00bb||||||||\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-191","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>directorio m\u00e9dico<\/title>\n<meta name=\"description\" content=\"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"directorio m\u00e9dico\" \/>\n<meta property=\"og:description\" content=\"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/\" \/>\n<meta property=\"og:site_name\" content=\"Zona de Salud San Bernardino\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T21:57:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/directorio-medico\\\/\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/directorio-medico\\\/\",\"name\":\"directorio m\u00e9dico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\"},\"datePublished\":\"2022-10-03T03:14:11+00:00\",\"dateModified\":\"2022-10-10T21:57:53+00:00\",\"description\":\"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/directorio-medico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/directorio-medico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/directorio-medico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Directorio m\u00e9dico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\",\"name\":\"Zona de Salud San Bernardino\",\"description\":\"Directorio de especialidades medicas y cl\u00ednicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"directorio m\u00e9dico","description":"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/","og_locale":"es_ES","og_type":"article","og_title":"directorio m\u00e9dico","og_description":"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.","og_url":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/","og_site_name":"Zona de Salud San Bernardino","article_modified_time":"2022-10-10T21:57:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/","url":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/","name":"directorio m\u00e9dico","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/#website"},"datePublished":"2022-10-03T03:14:11+00:00","dateModified":"2022-10-10T21:57:53+00:00","description":"Encuentra en el directorio m\u00e9dico los especialistas en medicina de la Fundaci\u00f3n San Bernardino en Distrito Capital.","breadcrumb":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/directorio-medico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saludsanbernardino.com.ve\/"},{"@type":"ListItem","position":2,"name":"Directorio m\u00e9dico"}]},{"@type":"WebSite","@id":"https:\/\/saludsanbernardino.com.ve\/#website","url":"https:\/\/saludsanbernardino.com.ve\/","name":"Zona de Salud San Bernardino","description":"Directorio de especialidades medicas y cl\u00ednicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saludsanbernardino.com.ve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/pages\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":82,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/pages\/191\/revisions"}],"predecessor-version":[{"id":1573,"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/pages\/191\/revisions\/1573"}],"wp:attachment":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/media?parent=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}