{"id":121,"count":1,"description":"","link":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/","name":"Internista","slug":"internista","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Internista archivos - Zona de Salud San Bernardino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Internista archivos - Zona de Salud San Bernardino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/\" \/>\n<meta property=\"og:site_name\" content=\"Zona de Salud San Bernardino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/category\\\/internista\\\/\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/category\\\/internista\\\/\",\"name\":\"Internista archivos - Zona de Salud San Bernardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/category\\\/internista\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/index.php\\\/category\\\/internista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/#website\",\"url\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/\",\"name\":\"Zona de Salud San Bernardino\",\"description\":\"Directorio de especialidades medicas y cl\u00ednicas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saludsanbernardino.com.ve\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Internista archivos - Zona de Salud San Bernardino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/","og_locale":"es_ES","og_type":"article","og_title":"Internista archivos - Zona de Salud San Bernardino","og_url":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/","og_site_name":"Zona de Salud San Bernardino","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/","url":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/","name":"Internista archivos - Zona de Salud San Bernardino","isPartOf":{"@id":"https:\/\/saludsanbernardino.com.ve\/#website"},"breadcrumb":{"@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/saludsanbernardino.com.ve\/index.php\/category\/internista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/saludsanbernardino.com.ve\/"},{"@type":"ListItem","position":2,"name":"Internista"}]},{"@type":"WebSite","@id":"https:\/\/saludsanbernardino.com.ve\/#website","url":"https:\/\/saludsanbernardino.com.ve\/","name":"Zona de Salud San Bernardino","description":"Directorio de especialidades medicas y cl\u00ednicas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saludsanbernardino.com.ve\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/categories\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/saludsanbernardino.com.ve\/index.php\/wp-json\/wp\/v2\/posts?categories=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}